{"id":93016,"count":1,"description":"","link":"https:\/\/archive.blogs.harvard.edu\/finearts\/category\/equity\/","name":"Equity","slug":"equity","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/archive.blogs.harvard.edu\/finearts\/wp-json\/wp\/v2\/categories\/93016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archive.blogs.harvard.edu\/finearts\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/archive.blogs.harvard.edu\/finearts\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/archive.blogs.harvard.edu\/finearts\/wp-json\/wp\/v2\/posts?categories=93016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}